{"id":8,"date":"2026-07-03T22:31:56","date_gmt":"2026-07-04T01:31:56","guid":{"rendered":"https:\/\/www.ce.ufpb.br\/dme\/?page_id=8"},"modified":"2026-08-02T19:26:07","modified_gmt":"2026-08-02T22:26:07","slug":"contato","status":"publish","type":"page","link":"https:\/\/www.ce.ufpb.br\/dme\/contato\/","title":{"rendered":"Contato"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>E-mail para atendimento ao p\u00fablico do setor:<\/strong> dme@ce.ufpb.br<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Telefone: <\/strong>(83) 3216-7446<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><div class=\"linha-header\">Hor\u00e1rios de Atendimento<\/div><\/h2>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Hor\u00e1rios de Atendimento da Secretaria do DME<\/summary>\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-6488bba6-9425-44eb-b270-100c00ddb816\" href=\"https:\/\/www.ce.ufpb.br\/dme\/wp-content\/uploads\/sites\/138\/sites\/500\/2026\/08\/Carta-de-servicos-DME-3.pdf\">Quadro de escala de atendimento da secretaria do DME<\/a><a href=\"https:\/\/www.ce.ufpb.br\/dme\/wp-content\/uploads\/sites\/138\/sites\/500\/2026\/08\/Carta-de-servicos-DME-3.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-6488bba6-9425-44eb-b270-100c00ddb816\">Baixar<\/a><\/div>\n<\/details>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary>Hor\u00e1rios de Atendimento da Chefia do DME<\/summary>\n<div class=\"wp-block-file\"><a id=\"wp-block-file--media-e935c7e9-d17d-4f12-8049-15cd093f3869\" href=\"https:\/\/www.ce.ufpb.br\/dme\/wp-content\/uploads\/sites\/138\/sites\/500\/2026\/08\/Carta-de-servicos-DME-4.pdf\">Quadro de escala de atendimento da chefia do DME<\/a><a href=\"https:\/\/www.ce.ufpb.br\/dme\/wp-content\/uploads\/sites\/138\/sites\/500\/2026\/08\/Carta-de-servicos-DME-4.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-e935c7e9-d17d-4f12-8049-15cd093f3869\">Baixar<\/a><\/div>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Endere\u00e7o do departamento:<\/strong><br>Universidade Federal da Para\u00edba, Centro de Educa\u00e7\u00e3o &#8211; Campus I, Departamento de<br>Metodologia da Educa\u00e7\u00e3o.<br>Universidade Federal da Para\u00edba &#8211; Campus I<br>Castelo Branco<br>58051900 &#8211; Jo\u00e3o Pessoa, PB &#8211; Brasil<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>E-mail para atendimento ao p\u00fablico do setor: dme@ce.ufpb.br Telefone: (83) 3216-7446 Hor\u00e1rios de Atendimento Endere\u00e7o [&hellip;]<\/p>\n","protected":false},"author":47,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/pages\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/comments?post=8"}],"version-history":[{"count":10,"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/pages\/8\/revisions"}],"predecessor-version":[{"id":360,"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/pages\/8\/revisions\/360"}],"wp:attachment":[{"href":"https:\/\/www.ce.ufpb.br\/dme\/wp-json\/wp\/v2\/media?parent=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}